{"id":44267,"date":"2025-05-06T18:26:40","date_gmt":"2025-05-06T21:26:40","guid":{"rendered":"https:\/\/ejornais.com.br\/index.php\/2025\/05\/06\/trajeto-da-rota-bioceanica-jardim-apresenta-demanda-de-infraestrutura-para-o-programa-ms-ativo\/"},"modified":"2025-05-06T18:26:40","modified_gmt":"2025-05-06T21:26:40","slug":"trajeto-da-rota-bioceanica-jardim-apresenta-demanda-de-infraestrutura-para-o-programa-ms-ativo","status":"publish","type":"post","link":"https:\/\/ejornais.com.br\/index.php\/2025\/05\/06\/trajeto-da-rota-bioceanica-jardim-apresenta-demanda-de-infraestrutura-para-o-programa-ms-ativo\/","title":{"rendered":"Trajeto da Rota Bioce\u00e2nica, Jardim apresenta demanda de infraestrutura para o programa MS Ativo"},"content":{"rendered":"<p><\/p>\n<div>\n<p>As a\u00e7\u00f5es e atua\u00e7\u00e3o do programa MS Ativo, com foco no municipalismo, continuam a ser realizadas em todo o Mato Grosso do Sul em projetos nas \u00e1reas de infraestrutura, sa\u00fade e educa\u00e7\u00e3o. E o trabalho j\u00e1 come\u00e7a a ser expandido para a melhoria das cidades do Estado.<\/p>\n<p>O governador Eduardo Riedel, em continuidade a agenda de trabalho na qual recebe as demandas e solicita\u00e7\u00f5es de todos os 79 munic\u00edpios, se reuniu \u2013 nesta ter\u00e7a-feira (6) \u2013 com o prefeito de Jardim, Juliano Miranda.<\/p>\n<p>\u201cA gente esperou passar quatro meses para o munic\u00edpio consolidar a equipe, entender a din\u00e2mica. A rela\u00e7\u00e3o com os munic\u00edpios surgiu anos atr\u00e1s, e com o MS Ativo consolidamos uma s\u00e9rie de a\u00e7\u00f5es em diretrizes estrat\u00e9gicas do Estado para que a gente mostre a sequ\u00eancia nesse processo de investimento. \u00c9 importante porque o Estado passa por um momento de transforma\u00e7\u00e3o e Jardim \u00e9 trajeto da Rota Bioce\u00e2nica\u201d, disse Riedel.<\/p>\n<div id=\"gallery-1\" class=\"gallery galleryid-509566 gallery-columns-2 gallery-size-full\">\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><\/div>\n<\/figure>\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><\/div>\n<\/figure><\/div>\n<p>O programa MS Ativo reafirma o compromisso do Governo do Estado com a efici\u00eancia da gest\u00e3o p\u00fablica e o desenvolvimento municipal, consolidando um modelo de parceria que promove crescimento econ\u00f4mico, infraestrutura moderna e melhores condi\u00e7\u00f5es de vida para os cidad\u00e3os sul-mato-grossenses.<\/p>\n<p>\u201cN\u00f3s temos 49% do munic\u00edpio sem pavimenta\u00e7\u00e3o. E nosso maior problema \u00e9 no Residencial S\u00e3o Paulo, toda vez que chove a gente tira de cinco a oito caminh\u00f5es de terra que descem nas ruas. Conversei com os vereadores e decidimos, com planejamento, que a prioridade para investimento \u00e9 em pavimenta\u00e7\u00e3o e drenagem, resolver essa quest\u00e3o\u201d, disse o prefeito.<\/p>\n<p>Atualmente, o munic\u00edpio de Jardim tem mais de R$ 82 milh\u00f5es em investimentos na \u00e1rea de sa\u00fade, educa\u00e7\u00e3o e infraestrutura, com investimentos do Governo do Estado.<\/p>\n<p>Tamb\u00e9m participaram da reuni\u00e3o o vice-governador Jos\u00e9 Carlos Barbosa (Barbosinha), al\u00e9m dos secret\u00e1rios Rodrigo Perez (Segov), Eduardo Rocha (Casa Civil) e Guilherme Alc\u00e2ntara (Seilog), al\u00e9m de deputados estaduais.<\/p>\n<div id=\"gallery-2\" class=\"gallery galleryid-509566 gallery-columns-2 gallery-size-full\">\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><\/div>\n<\/figure>\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><\/div>\n<\/figure><\/div>\n<p><em>Natalia Yahn, Comunica\u00e7\u00e3o Governo de MS<\/em><br \/><em>Fotos: Saul Schramm<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>As a\u00e7\u00f5es e atua\u00e7\u00e3o do programa MS Ativo, com foco no municipalismo, continuam a ser realizadas em todo o Mato<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-44267","post","type-post","status-publish","format-standard","hentry","category-ejornais"],"aioseo_notices":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts\/44267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=44267"}],"version-history":[{"count":0,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts\/44267\/revisions"}],"wp:attachment":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=44267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=44267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=44267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}