{"id":59887,"date":"2026-01-30T07:22:00","date_gmt":"2026-01-30T10:22:00","guid":{"rendered":"https:\/\/ejornais.com.br\/index.php\/2026\/01\/30\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\/"},"modified":"2026-01-30T07:22:00","modified_gmt":"2026-01-30T10:22:00","slug":"agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro","status":"publish","type":"post","link":"https:\/\/ejornais.com.br\/index.php\/2026\/01\/30\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\/","title":{"rendered":"Ag\u00eancia Minas Gerais | Previs\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro"},"content":{"rendered":"<p><\/p>\n<div>\n<p>Nesta sexta-feira, uma \u00e1rea de baixa press\u00e3o se forma no litoral paulista, intensificando as instabilidades inicialmente no centro-sul e oeste de Minas Gerais. Nas demais regi\u00f5es mineiras, as t\u00edpicas pancadas de ver\u00e3o devem ocorrer principalmente a tarde. A partir de s\u00e1bado, todo o estado tende a ficar nublado com condi\u00e7\u00f5es de chuva a qualquer hora. Situa\u00e7\u00e3o que deve persistir at\u00e9 aproximadamente ter\u00e7a-feira (3\/2).<\/p>\n<p>Clique aqui\u00a0para conferir a previs\u00e3o completa do Instituto Nacional de Meteorologia (Inmet).\u00a0<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nesta sexta-feira, uma \u00e1rea de baixa press\u00e3o se forma no litoral paulista, intensificando as instabilidades inicialmente no centro-sul e oeste<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-59887","post","type-post","status-publish","format-standard","hentry","category-ejornais"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Nesta sexta-feira, uma \u00e1rea de baixa press\u00e3o se forma no litoral paulista, intensificando as instabilidades inicialmente no centro-sul e oeste de Minas Gerais. Nas demais regi\u00f5es mineiras, as t\u00edpicas pancadas de ver\u00e3o devem ocorrer principalmente a tarde. A partir de s\u00e1bado, todo o estado tende a ficar nublado com condi\u00e7\u00f5es de chuva a qualquer hora.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ejornais.com.br\/index.php\/2026\/01\/30\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"eJornais - Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ag\u00eancia Minas Gerais | Previs\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro - eJornais\" \/>\n\t\t<meta property=\"og:description\" content=\"Nesta sexta-feira, uma \u00e1rea de baixa press\u00e3o se forma no litoral paulista, intensificando as instabilidades inicialmente no centro-sul e oeste de Minas Gerais. Nas demais regi\u00f5es mineiras, as t\u00edpicas pancadas de ver\u00e3o devem ocorrer principalmente a tarde. A partir de s\u00e1bado, todo o estado tende a ficar nublado com condi\u00e7\u00f5es de chuva a qualquer hora.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ejornais.com.br\/index.php\/2026\/01\/30\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-01-30T10:22:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-01-30T10:22:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ag\u00eancia Minas Gerais | Previs\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro - eJornais\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Nesta sexta-feira, uma \u00e1rea de baixa press\u00e3o se forma no litoral paulista, intensificando as instabilidades inicialmente no centro-sul e oeste de Minas Gerais. Nas demais regi\u00f5es mineiras, as t\u00edpicas pancadas de ver\u00e3o devem ocorrer principalmente a tarde. A partir de s\u00e1bado, todo o estado tende a ficar nublado com condi\u00e7\u00f5es de chuva a qualquer hora.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/01\\\/30\\\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\\\/#blogposting\",\"name\":\"Ag\\u00eancia Minas Gerais | Previs\\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro - eJornais\",\"headline\":\"Ag\\u00eancia Minas Gerais | Previs\\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro\",\"author\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#organization\"},\"datePublished\":\"2026-01-30T07:22:00-03:00\",\"dateModified\":\"2026-01-30T07:22:00-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/01\\\/30\\\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/01\\\/30\\\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\\\/#webpage\"},\"articleSection\":\"Cat\\u00e1logo de Jornais\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/01\\\/30\\\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/ejornais.com.br\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/#listItem\",\"name\":\"Cat\\u00e1logo de Jornais\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/#listItem\",\"position\":2,\"name\":\"Cat\\u00e1logo de Jornais\",\"item\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/01\\\/30\\\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\\\/#listItem\",\"name\":\"Ag\\u00eancia Minas Gerais | Previs\\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/01\\\/30\\\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\\\/#listItem\",\"position\":3,\"name\":\"Ag\\u00eancia Minas Gerais | Previs\\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/#listItem\",\"name\":\"Cat\\u00e1logo de Jornais\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#organization\",\"name\":\"eJornais\",\"description\":\"Cat\\u00e1logo de Jornais no mundo, Not\\u00edcias, Blog e Esportes ao vivo\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/\",\"name\":\"admin1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/01\\\/30\\\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/01\\\/30\\\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\\\/#webpage\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/01\\\/30\\\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\\\/\",\"name\":\"Ag\\u00eancia Minas Gerais | Previs\\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro - eJornais\",\"description\":\"Nesta sexta-feira, uma \\u00e1rea de baixa press\\u00e3o se forma no litoral paulista, intensificando as instabilidades inicialmente no centro-sul e oeste de Minas Gerais. Nas demais regi\\u00f5es mineiras, as t\\u00edpicas pancadas de ver\\u00e3o devem ocorrer principalmente a tarde. A partir de s\\u00e1bado, todo o estado tende a ficar nublado com condi\\u00e7\\u00f5es de chuva a qualquer hora.\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/01\\\/30\\\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\"},\"datePublished\":\"2026-01-30T07:22:00-03:00\",\"dateModified\":\"2026-01-30T07:22:00-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#website\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/\",\"name\":\"eJornais\",\"description\":\"Cat\\u00e1logo de Jornais no mundo, Not\\u00edcias, Blog e Esportes ao vivo\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ag\u00eancia Minas Gerais | Previs\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro - eJornais","description":"Nesta sexta-feira, uma \u00e1rea de baixa press\u00e3o se forma no litoral paulista, intensificando as instabilidades inicialmente no centro-sul e oeste de Minas Gerais. Nas demais regi\u00f5es mineiras, as t\u00edpicas pancadas de ver\u00e3o devem ocorrer principalmente a tarde. A partir de s\u00e1bado, todo o estado tende a ficar nublado com condi\u00e7\u00f5es de chuva a qualquer hora.","canonical_url":"https:\/\/ejornais.com.br\/index.php\/2026\/01\/30\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/01\/30\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\/#blogposting","name":"Ag\u00eancia Minas Gerais | Previs\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro - eJornais","headline":"Ag\u00eancia Minas Gerais | Previs\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro","author":{"@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author"},"publisher":{"@id":"https:\/\/ejornais.com.br\/#organization"},"datePublished":"2026-01-30T07:22:00-03:00","dateModified":"2026-01-30T07:22:00-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/ejornais.com.br\/index.php\/2026\/01\/30\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\/#webpage"},"isPartOf":{"@id":"https:\/\/ejornais.com.br\/index.php\/2026\/01\/30\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\/#webpage"},"articleSection":"Cat\u00e1logo de Jornais"},{"@type":"BreadcrumbList","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/01\/30\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ejornais.com.br#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/ejornais.com.br","nextItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/#listItem","name":"Cat\u00e1logo de Jornais"}},{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/#listItem","position":2,"name":"Cat\u00e1logo de Jornais","item":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/01\/30\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\/#listItem","name":"Ag\u00eancia Minas Gerais | Previs\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/01\/30\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\/#listItem","position":3,"name":"Ag\u00eancia Minas Gerais | Previs\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro","previousItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/#listItem","name":"Cat\u00e1logo de Jornais"}}]},{"@type":"Organization","@id":"https:\/\/ejornais.com.br\/#organization","name":"eJornais","description":"Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo","url":"https:\/\/ejornais.com.br\/"},{"@type":"Person","@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author","url":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/","name":"admin1","image":{"@type":"ImageObject","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/01\/30\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin1"}},{"@type":"WebPage","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/01\/30\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\/#webpage","url":"https:\/\/ejornais.com.br\/index.php\/2026\/01\/30\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\/","name":"Ag\u00eancia Minas Gerais | Previs\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro - eJornais","description":"Nesta sexta-feira, uma \u00e1rea de baixa press\u00e3o se forma no litoral paulista, intensificando as instabilidades inicialmente no centro-sul e oeste de Minas Gerais. Nas demais regi\u00f5es mineiras, as t\u00edpicas pancadas de ver\u00e3o devem ocorrer principalmente a tarde. A partir de s\u00e1bado, todo o estado tende a ficar nublado com condi\u00e7\u00f5es de chuva a qualquer hora.","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/ejornais.com.br\/#website"},"breadcrumb":{"@id":"https:\/\/ejornais.com.br\/index.php\/2026\/01\/30\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\/#breadcrumblist"},"author":{"@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author"},"creator":{"@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author"},"datePublished":"2026-01-30T07:22:00-03:00","dateModified":"2026-01-30T07:22:00-03:00"},{"@type":"WebSite","@id":"https:\/\/ejornais.com.br\/#website","url":"https:\/\/ejornais.com.br\/","name":"eJornais","description":"Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/ejornais.com.br\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"eJornais - Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo","og:type":"article","og:title":"Ag\u00eancia Minas Gerais | Previs\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro - eJornais","og:description":"Nesta sexta-feira, uma \u00e1rea de baixa press\u00e3o se forma no litoral paulista, intensificando as instabilidades inicialmente no centro-sul e oeste de Minas Gerais. Nas demais regi\u00f5es mineiras, as t\u00edpicas pancadas de ver\u00e3o devem ocorrer principalmente a tarde. A partir de s\u00e1bado, todo o estado tende a ficar nublado com condi\u00e7\u00f5es de chuva a qualquer hora.","og:url":"https:\/\/ejornais.com.br\/index.php\/2026\/01\/30\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\/","article:published_time":"2026-01-30T10:22:00+00:00","article:modified_time":"2026-01-30T10:22:00+00:00","twitter:card":"summary_large_image","twitter:title":"Ag\u00eancia Minas Gerais | Previs\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro - eJornais","twitter:description":"Nesta sexta-feira, uma \u00e1rea de baixa press\u00e3o se forma no litoral paulista, intensificando as instabilidades inicialmente no centro-sul e oeste de Minas Gerais. Nas demais regi\u00f5es mineiras, as t\u00edpicas pancadas de ver\u00e3o devem ocorrer principalmente a tarde. A partir de s\u00e1bado, todo o estado tende a ficar nublado com condi\u00e7\u00f5es de chuva a qualquer hora."},"aioseo_meta_data":{"post_id":"59887","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-01-30 10:33:58","updated":"2026-01-30 10:33:58","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ejornais.com.br\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/\" title=\"Cat\u00e1logo de Jornais\">Cat\u00e1logo de Jornais<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAg\u00eancia Minas Gerais | Previs\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/ejornais.com.br"},{"label":"Cat\u00e1logo de Jornais","link":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/"},{"label":"Ag\u00eancia Minas Gerais | Previs\u00e3o do tempo para Minas Gerais nesta sexta, 30 de janeiro","link":"https:\/\/ejornais.com.br\/index.php\/2026\/01\/30\/agencia-minas-gerais-previsao-do-tempo-para-minas-gerais-nesta-sexta-30-de-janeiro\/"}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=59887"}],"version-history":[{"count":0,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59887\/revisions"}],"wp:attachment":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=59887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=59887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=59887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}