{"id":69057,"date":"2026-07-13T21:06:55","date_gmt":"2026-07-14T00:06:55","guid":{"rendered":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\/"},"modified":"2026-07-13T21:06:55","modified_gmt":"2026-07-14T00:06:55","slug":"seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2","status":"publish","type":"post","link":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\/","title":{"rendered":"Seinfra realiza manuten\u00e7\u00e3o na malha vi\u00e1ria, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica"},"content":{"rendered":"<p><\/p>\n<div>\n<p>A Secretaria de Infraestrutura de Jo\u00e3o Pessoa (Seinfra) segue com o cronograma de servi\u00e7os de manuten\u00e7\u00e3o, como tapa-buraco, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica, nesta ter\u00e7a-feira (14), em 43 bairros da Capital. Esses trabalhos s\u00e3o realizados diariamente pela Diretoria de Manuten\u00e7\u00e3o Vi\u00e1ria e Drenagem e atende \u00e0s demandas da popula\u00e7\u00e3o para melhorar a qualidade da malha vi\u00e1ria da cidade.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><\/figure>\n<figure class=\"wp-block-image size-large\"><\/figure>\n<\/figure>\n<p>A partir das 8h, as equipes da tapa-buraco estar\u00e3o trabalhando nos seguintes bairros: Jardim Cidade Universit\u00e1ria, Bairro dos Estados, Cristo Redentor, Jo\u00e3o Paulo II, Gramame, Mangabeira, Valentina Figueiredo,\u00a0 Ernesto Geisel,\u00a0 Cabo Branco, Tambi\u00e1, Bairro dos Ip\u00eas, Jaguaribe, Mandacaru, Bairro das Ind\u00fastrias, Distrito Industrial,\u00a0 Torre,\u00a0\u00a0 Jos\u00e9 Am\u00e9rico, Bessa, Jardim Oceania, Mana\u00edra, Varadouro, Tambauzinho, Treze de Maio, Ilha do Bispo, Pedro Gondim, Miramar, Planalto Boa Esperan\u00e7a, Banc\u00e1rios, Tamba\u00fa, Aeroclube, Cui\u00e1, \u00c1gua Fria, Funcion\u00e1rios, Alto do Mateus, Costa e Silva, Ernani S\u00e1tiro, Varj\u00e3o, Cruz das Armas, Paratibe, Altiplano, Jardim Veneza e Mumbaba.<\/p>\n<p>As equipes de ilumina\u00e7\u00e3o p\u00fablica tamb\u00e9m est\u00e3o realizando, nesta ter\u00e7a-feira, manuten\u00e7\u00e3o no Bairro das Ind\u00fastrias, Mumbaba, Engenho Velho, Altiplano e Mangabeira.<\/p>\n<p>J\u00e1 a manuten\u00e7\u00e3o na rede de drenagem acontece em diversos bairros com servi\u00e7os de limpeza e desobstru\u00e7\u00e3o de galerias, extens\u00e3o de rede, adequa\u00e7\u00e3o e manuten\u00e7\u00e3o de bocas de lobo e reposi\u00e7\u00e3o de grelhas.<\/p>\n<p><strong>Como solicitar os servi\u00e7os \u2013<\/strong> As demandas como manuten\u00e7\u00e3o de vias, de ilumina\u00e7\u00e3o p\u00fablica e galerias devem ser solicitadas por meio do aplicativo \u2018Jo\u00e3o Pessoa na Palma da M\u00e3o\u2019. A ferramenta est\u00e1 dispon\u00edvel para dispositivos m\u00f3veis, que possibilita ao cidad\u00e3o acessar todos os servi\u00e7os da Prefeitura de Jo\u00e3o Pessoa de forma mais \u00e1gil, segura e sem a necessidade de sair de casa.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Infraestrutura de Jo\u00e3o Pessoa (Seinfra) segue com o cronograma de servi\u00e7os de manuten\u00e7\u00e3o, como tapa-buraco, rede de<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-69057","post","type-post","status-publish","format-standard","hentry","category-ejornais"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"A Secretaria de Infraestrutura de Jo\u00e3o Pessoa (Seinfra) segue com o cronograma de servi\u00e7os de manuten\u00e7\u00e3o, como tapa-buraco, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica, nesta ter\u00e7a-feira (14), em 43 bairros da Capital. Esses trabalhos s\u00e3o realizados diariamente pela Diretoria de Manuten\u00e7\u00e3o Vi\u00e1ria e Drenagem e atende \u00e0s demandas da popula\u00e7\u00e3o para melhorar a qualidade da\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"eJornais - Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Seinfra realiza manuten\u00e7\u00e3o na malha vi\u00e1ria, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica - eJornais\" \/>\n\t\t<meta property=\"og:description\" content=\"A Secretaria de Infraestrutura de Jo\u00e3o Pessoa (Seinfra) segue com o cronograma de servi\u00e7os de manuten\u00e7\u00e3o, como tapa-buraco, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica, nesta ter\u00e7a-feira (14), em 43 bairros da Capital. Esses trabalhos s\u00e3o realizados diariamente pela Diretoria de Manuten\u00e7\u00e3o Vi\u00e1ria e Drenagem e atende \u00e0s demandas da popula\u00e7\u00e3o para melhorar a qualidade da\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-14T00:06:55+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-14T00:06:55+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Seinfra realiza manuten\u00e7\u00e3o na malha vi\u00e1ria, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica - eJornais\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A Secretaria de Infraestrutura de Jo\u00e3o Pessoa (Seinfra) segue com o cronograma de servi\u00e7os de manuten\u00e7\u00e3o, como tapa-buraco, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica, nesta ter\u00e7a-feira (14), em 43 bairros da Capital. Esses trabalhos s\u00e3o realizados diariamente pela Diretoria de Manuten\u00e7\u00e3o Vi\u00e1ria e Drenagem e atende \u00e0s demandas da popula\u00e7\u00e3o para melhorar a qualidade da\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\\\/#blogposting\",\"name\":\"Seinfra realiza manuten\\u00e7\\u00e3o na malha vi\\u00e1ria, rede de drenagem e ilumina\\u00e7\\u00e3o p\\u00fablica - eJornais\",\"headline\":\"Seinfra realiza manuten\\u00e7\\u00e3o na malha vi\\u00e1ria, rede de drenagem e ilumina\\u00e7\\u00e3o p\\u00fablica\",\"author\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#organization\"},\"datePublished\":\"2026-07-13T21:06:55-03:00\",\"dateModified\":\"2026-07-13T21:06:55-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\\\/#webpage\"},\"articleSection\":\"Cat\\u00e1logo de Jornais\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/ejornais.com.br\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/#listItem\",\"name\":\"Cat\\u00e1logo de Jornais\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/#listItem\",\"position\":2,\"name\":\"Cat\\u00e1logo de Jornais\",\"item\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\\\/#listItem\",\"name\":\"Seinfra realiza manuten\\u00e7\\u00e3o na malha vi\\u00e1ria, rede de drenagem e ilumina\\u00e7\\u00e3o p\\u00fablica\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\\\/#listItem\",\"position\":3,\"name\":\"Seinfra realiza manuten\\u00e7\\u00e3o na malha vi\\u00e1ria, rede de drenagem e ilumina\\u00e7\\u00e3o p\\u00fablica\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/#listItem\",\"name\":\"Cat\\u00e1logo de Jornais\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#organization\",\"name\":\"eJornais\",\"description\":\"Cat\\u00e1logo de Jornais no mundo, Not\\u00edcias, Blog e Esportes ao vivo\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/\",\"name\":\"admin1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\\\/\",\"name\":\"Seinfra realiza manuten\\u00e7\\u00e3o na malha vi\\u00e1ria, rede de drenagem e ilumina\\u00e7\\u00e3o p\\u00fablica - eJornais\",\"description\":\"A Secretaria de Infraestrutura de Jo\\u00e3o Pessoa (Seinfra) segue com o cronograma de servi\\u00e7os de manuten\\u00e7\\u00e3o, como tapa-buraco, rede de drenagem e ilumina\\u00e7\\u00e3o p\\u00fablica, nesta ter\\u00e7a-feira (14), em 43 bairros da Capital. Esses trabalhos s\\u00e3o realizados diariamente pela Diretoria de Manuten\\u00e7\\u00e3o Vi\\u00e1ria e Drenagem e atende \\u00e0s demandas da popula\\u00e7\\u00e3o para melhorar a qualidade da\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\"},\"datePublished\":\"2026-07-13T21:06:55-03:00\",\"dateModified\":\"2026-07-13T21:06:55-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#website\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/\",\"name\":\"eJornais\",\"description\":\"Cat\\u00e1logo de Jornais no mundo, Not\\u00edcias, Blog e Esportes ao vivo\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Seinfra realiza manuten\u00e7\u00e3o na malha vi\u00e1ria, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica - eJornais","description":"A Secretaria de Infraestrutura de Jo\u00e3o Pessoa (Seinfra) segue com o cronograma de servi\u00e7os de manuten\u00e7\u00e3o, como tapa-buraco, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica, nesta ter\u00e7a-feira (14), em 43 bairros da Capital. Esses trabalhos s\u00e3o realizados diariamente pela Diretoria de Manuten\u00e7\u00e3o Vi\u00e1ria e Drenagem e atende \u00e0s demandas da popula\u00e7\u00e3o para melhorar a qualidade da","canonical_url":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\/#blogposting","name":"Seinfra realiza manuten\u00e7\u00e3o na malha vi\u00e1ria, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica - eJornais","headline":"Seinfra realiza manuten\u00e7\u00e3o na malha vi\u00e1ria, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica","author":{"@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author"},"publisher":{"@id":"https:\/\/ejornais.com.br\/#organization"},"datePublished":"2026-07-13T21:06:55-03:00","dateModified":"2026-07-13T21:06:55-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\/#webpage"},"articleSection":"Cat\u00e1logo de Jornais"},{"@type":"BreadcrumbList","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ejornais.com.br#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/ejornais.com.br","nextItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/#listItem","name":"Cat\u00e1logo de Jornais"}},{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/#listItem","position":2,"name":"Cat\u00e1logo de Jornais","item":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\/#listItem","name":"Seinfra realiza manuten\u00e7\u00e3o na malha vi\u00e1ria, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\/#listItem","position":3,"name":"Seinfra realiza manuten\u00e7\u00e3o na malha vi\u00e1ria, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica","previousItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/#listItem","name":"Cat\u00e1logo de Jornais"}}]},{"@type":"Organization","@id":"https:\/\/ejornais.com.br\/#organization","name":"eJornais","description":"Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo","url":"https:\/\/ejornais.com.br\/"},{"@type":"Person","@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author","url":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/","name":"admin1","image":{"@type":"ImageObject","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin1"}},{"@type":"WebPage","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\/#webpage","url":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\/","name":"Seinfra realiza manuten\u00e7\u00e3o na malha vi\u00e1ria, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica - eJornais","description":"A Secretaria de Infraestrutura de Jo\u00e3o Pessoa (Seinfra) segue com o cronograma de servi\u00e7os de manuten\u00e7\u00e3o, como tapa-buraco, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica, nesta ter\u00e7a-feira (14), em 43 bairros da Capital. Esses trabalhos s\u00e3o realizados diariamente pela Diretoria de Manuten\u00e7\u00e3o Vi\u00e1ria e Drenagem e atende \u00e0s demandas da popula\u00e7\u00e3o para melhorar a qualidade da","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/ejornais.com.br\/#website"},"breadcrumb":{"@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author"},"creator":{"@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author"},"datePublished":"2026-07-13T21:06:55-03:00","dateModified":"2026-07-13T21:06:55-03:00"},{"@type":"WebSite","@id":"https:\/\/ejornais.com.br\/#website","url":"https:\/\/ejornais.com.br\/","name":"eJornais","description":"Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/ejornais.com.br\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"eJornais - Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo","og:type":"article","og:title":"Seinfra realiza manuten\u00e7\u00e3o na malha vi\u00e1ria, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica - eJornais","og:description":"A Secretaria de Infraestrutura de Jo\u00e3o Pessoa (Seinfra) segue com o cronograma de servi\u00e7os de manuten\u00e7\u00e3o, como tapa-buraco, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica, nesta ter\u00e7a-feira (14), em 43 bairros da Capital. Esses trabalhos s\u00e3o realizados diariamente pela Diretoria de Manuten\u00e7\u00e3o Vi\u00e1ria e Drenagem e atende \u00e0s demandas da popula\u00e7\u00e3o para melhorar a qualidade da","og:url":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\/","article:published_time":"2026-07-14T00:06:55+00:00","article:modified_time":"2026-07-14T00:06:55+00:00","twitter:card":"summary_large_image","twitter:title":"Seinfra realiza manuten\u00e7\u00e3o na malha vi\u00e1ria, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica - eJornais","twitter:description":"A Secretaria de Infraestrutura de Jo\u00e3o Pessoa (Seinfra) segue com o cronograma de servi\u00e7os de manuten\u00e7\u00e3o, como tapa-buraco, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica, nesta ter\u00e7a-feira (14), em 43 bairros da Capital. Esses trabalhos s\u00e3o realizados diariamente pela Diretoria de Manuten\u00e7\u00e3o Vi\u00e1ria e Drenagem e atende \u00e0s demandas da popula\u00e7\u00e3o para melhorar a qualidade da"},"aioseo_meta_data":[],"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ejornais.com.br\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/\" title=\"Cat\u00e1logo de Jornais\">Cat\u00e1logo de Jornais<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSeinfra realiza manuten\u00e7\u00e3o na malha vi\u00e1ria, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/ejornais.com.br"},{"label":"Cat\u00e1logo de Jornais","link":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/"},{"label":"Seinfra realiza manuten\u00e7\u00e3o na malha vi\u00e1ria, rede de drenagem e ilumina\u00e7\u00e3o p\u00fablica","link":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/seinfra-realiza-manutencao-na-malha-viaria-rede-de-drenagem-e-iluminacao-publica-2\/"}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts\/69057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=69057"}],"version-history":[{"count":0,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts\/69057\/revisions"}],"wp:attachment":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=69057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=69057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=69057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}