{"id":69058,"date":"2026-07-13T21:33:47","date_gmt":"2026-07-14T00:33:47","guid":{"rendered":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/"},"modified":"2026-07-13T21:33:47","modified_gmt":"2026-07-14T00:33:47","slug":"invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado","status":"publish","type":"post","link":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/","title":{"rendered":"Invictas, sele\u00e7\u00f5es do Brasil jogam oitavas do Mundial de v\u00f4lei sentado"},"content":{"rendered":"<p> Por MRNews<br \/>\n<\/p>\n<div>\n<p>As sele\u00e7\u00f5es masculina e feminina de v\u00f4lei sentado, que disputam o Campeonato Mundial da modalidade em Hanghzou (China), voltam a quadra na madrugada desta ter\u00e7a-feira (14), pelas oitavas de final dos respectivos torneios.<\/p>\n<p>Entre os homens, que buscam um t\u00edtulo in\u00e9dito, o desafio brasileiro ser\u00e1 contra o Jap\u00e3o, a partir das 2h30 (hor\u00e1rio de Bras\u00edlia). J\u00e1 \u00e0s 3h, as mulheres do Brasil, atuais campe\u00e3s, encaram com a Hungria para seguirem na disputa pelo bi.<\/p>\n<p>As duas equipes est\u00e3o invictas. A equipe masculina encerrou a participa\u00e7\u00e3o na primeira fase ao vencer a Cro\u00e1cia por 3 sets a 0 (25\/20, 25\/21 e 25\/14) nas primeiras horas desta segunda-feira (13). A equipe feminina, tamb\u00e9m na \u00faltima madrugada, derrotou a Fran\u00e7a pelo mesmo placar, mas com parciais de 25\/12, 25\/9 e 25\/5.<\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/07\/13\/bolsa-cai-12-e-dolar-sobe-para-r-513-com-tensao-global\/\">Bolsa cai 1,2%, e d\u00f3lar sobe para R$ 5,13 com tens\u00e3o global<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/07\/13\/palmeiras-conquista-ladies-cup-antes-da-volta-do-brasileiro-feminino\/\">Palmeiras conquista Ladies Cup antes da volta do Brasileiro Feminino<\/a><\/strong><\/p>\n<p>O Mundial re\u00fane 16 sele\u00e7\u00f5es em cada naipe, divididas em quatro chaves de quatro times cada, que jogam entre si. A etapa de grupos serve para definir os confrontos das oitavas de final, pois todos os participantes avan\u00e7am \u00e0s oitavas de final.<\/p>\n<p>No masculino, o Brasil foi o primeiro do Grupo C, com tr\u00eas vit\u00f3rias, seguido por Cazaquist\u00e3o (dois triunfos), Iraque (um) e Cro\u00e1cia (zero). O Jap\u00e3o, rival das oitavas, ficou em \u00faltimo lugar do Grupo D, passando em branco nas partidas contra Estados Unidos, Ucr\u00e2nia e Alemanha.<\/p>\n<p>Na disputa feminina, as brasileiras n\u00e3o perderam nenhum set e tamb\u00e9m atingiram 100% de aproveitamento na lideran\u00e7a do Grupo D, com a It\u00e1lia em segundo (duas vit\u00f3rias), a Tail\u00e2ndia em terceiro (uma) e a Fran\u00e7a em \u00faltimo. As h\u00fangaras, advers\u00e1rias das atuais campe\u00e3s, foram as lanternas do Grupo C, sem triunfos sobre Canad\u00e1, Jap\u00e3o e Eslov\u00eania.<\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/07\/13\/rivalidade-entre-argentina-e-inglaterra-extrapola-as-quatro-linhas\/\">Rivalidade entre Argentina e Inglaterra extrapola as quatro linhas<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/07\/13\/operacao-resgata-29-trabalhadores-em-condicoes-analogas-a-escravidao\/\">Opera\u00e7\u00e3o resgata 29 trabalhadores em condi\u00e7\u00f5es an\u00e1logas \u00e0 escravid\u00e3o<\/a><\/strong><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por MRNews As sele\u00e7\u00f5es masculina e feminina de v\u00f4lei sentado, que disputam o Campeonato Mundial da modalidade em Hanghzou (China),<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-69058","post","type-post","status-publish","format-standard","hentry","category-ejornais"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Por MRNews As sele\u00e7\u00f5es masculina e feminina de v\u00f4lei sentado, que disputam o Campeonato Mundial da modalidade em Hanghzou (China), voltam a quadra na madrugada desta ter\u00e7a-feira (14), pelas oitavas de final dos respectivos torneios. Entre os homens, que buscam um t\u00edtulo in\u00e9dito, o desafio brasileiro ser\u00e1 contra o Jap\u00e3o, a partir das 2h30 (hor\u00e1rio\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"eJornais - Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Invictas, sele\u00e7\u00f5es do Brasil jogam oitavas do Mundial de v\u00f4lei sentado - eJornais\" \/>\n\t\t<meta property=\"og:description\" content=\"Por MRNews As sele\u00e7\u00f5es masculina e feminina de v\u00f4lei sentado, que disputam o Campeonato Mundial da modalidade em Hanghzou (China), voltam a quadra na madrugada desta ter\u00e7a-feira (14), pelas oitavas de final dos respectivos torneios. Entre os homens, que buscam um t\u00edtulo in\u00e9dito, o desafio brasileiro ser\u00e1 contra o Jap\u00e3o, a partir das 2h30 (hor\u00e1rio\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-14T00:33:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-14T00:33:47+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Invictas, sele\u00e7\u00f5es do Brasil jogam oitavas do Mundial de v\u00f4lei sentado - eJornais\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Por MRNews As sele\u00e7\u00f5es masculina e feminina de v\u00f4lei sentado, que disputam o Campeonato Mundial da modalidade em Hanghzou (China), voltam a quadra na madrugada desta ter\u00e7a-feira (14), pelas oitavas de final dos respectivos torneios. Entre os homens, que buscam um t\u00edtulo in\u00e9dito, o desafio brasileiro ser\u00e1 contra o Jap\u00e3o, a partir das 2h30 (hor\u00e1rio\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\\\/#blogposting\",\"name\":\"Invictas, sele\\u00e7\\u00f5es do Brasil jogam oitavas do Mundial de v\\u00f4lei sentado - eJornais\",\"headline\":\"Invictas, sele\\u00e7\\u00f5es do Brasil jogam oitavas do Mundial de v\\u00f4lei sentado\",\"author\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#organization\"},\"datePublished\":\"2026-07-13T21:33:47-03:00\",\"dateModified\":\"2026-07-13T21:33:47-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\\\/#webpage\"},\"articleSection\":\"Cat\\u00e1logo de Jornais\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/ejornais.com.br\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/#listItem\",\"name\":\"Cat\\u00e1logo de Jornais\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/#listItem\",\"position\":2,\"name\":\"Cat\\u00e1logo de Jornais\",\"item\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\\\/#listItem\",\"name\":\"Invictas, sele\\u00e7\\u00f5es do Brasil jogam oitavas do Mundial de v\\u00f4lei sentado\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\\\/#listItem\",\"position\":3,\"name\":\"Invictas, sele\\u00e7\\u00f5es do Brasil jogam oitavas do Mundial de v\\u00f4lei sentado\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/#listItem\",\"name\":\"Cat\\u00e1logo de Jornais\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#organization\",\"name\":\"eJornais\",\"description\":\"Cat\\u00e1logo de Jornais no mundo, Not\\u00edcias, Blog e Esportes ao vivo\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/\",\"name\":\"admin1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\\\/#webpage\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\\\/\",\"name\":\"Invictas, sele\\u00e7\\u00f5es do Brasil jogam oitavas do Mundial de v\\u00f4lei sentado - eJornais\",\"description\":\"Por MRNews As sele\\u00e7\\u00f5es masculina e feminina de v\\u00f4lei sentado, que disputam o Campeonato Mundial da modalidade em Hanghzou (China), voltam a quadra na madrugada desta ter\\u00e7a-feira (14), pelas oitavas de final dos respectivos torneios. Entre os homens, que buscam um t\\u00edtulo in\\u00e9dito, o desafio brasileiro ser\\u00e1 contra o Jap\\u00e3o, a partir das 2h30 (hor\\u00e1rio\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/13\\\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\"},\"datePublished\":\"2026-07-13T21:33:47-03:00\",\"dateModified\":\"2026-07-13T21:33:47-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#website\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/\",\"name\":\"eJornais\",\"description\":\"Cat\\u00e1logo de Jornais no mundo, Not\\u00edcias, Blog e Esportes ao vivo\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Invictas, sele\u00e7\u00f5es do Brasil jogam oitavas do Mundial de v\u00f4lei sentado - eJornais","description":"Por MRNews As sele\u00e7\u00f5es masculina e feminina de v\u00f4lei sentado, que disputam o Campeonato Mundial da modalidade em Hanghzou (China), voltam a quadra na madrugada desta ter\u00e7a-feira (14), pelas oitavas de final dos respectivos torneios. Entre os homens, que buscam um t\u00edtulo in\u00e9dito, o desafio brasileiro ser\u00e1 contra o Jap\u00e3o, a partir das 2h30 (hor\u00e1rio","canonical_url":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/#blogposting","name":"Invictas, sele\u00e7\u00f5es do Brasil jogam oitavas do Mundial de v\u00f4lei sentado - eJornais","headline":"Invictas, sele\u00e7\u00f5es do Brasil jogam oitavas do Mundial de v\u00f4lei sentado","author":{"@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author"},"publisher":{"@id":"https:\/\/ejornais.com.br\/#organization"},"datePublished":"2026-07-13T21:33:47-03:00","dateModified":"2026-07-13T21:33:47-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/#webpage"},"isPartOf":{"@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/#webpage"},"articleSection":"Cat\u00e1logo de Jornais"},{"@type":"BreadcrumbList","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ejornais.com.br#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/ejornais.com.br","nextItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/#listItem","name":"Cat\u00e1logo de Jornais"}},{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/#listItem","position":2,"name":"Cat\u00e1logo de Jornais","item":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/#listItem","name":"Invictas, sele\u00e7\u00f5es do Brasil jogam oitavas do Mundial de v\u00f4lei sentado"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/#listItem","position":3,"name":"Invictas, sele\u00e7\u00f5es do Brasil jogam oitavas do Mundial de v\u00f4lei sentado","previousItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/#listItem","name":"Cat\u00e1logo de Jornais"}}]},{"@type":"Organization","@id":"https:\/\/ejornais.com.br\/#organization","name":"eJornais","description":"Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo","url":"https:\/\/ejornais.com.br\/"},{"@type":"Person","@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author","url":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/","name":"admin1","image":{"@type":"ImageObject","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin1"}},{"@type":"WebPage","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/#webpage","url":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/","name":"Invictas, sele\u00e7\u00f5es do Brasil jogam oitavas do Mundial de v\u00f4lei sentado - eJornais","description":"Por MRNews As sele\u00e7\u00f5es masculina e feminina de v\u00f4lei sentado, que disputam o Campeonato Mundial da modalidade em Hanghzou (China), voltam a quadra na madrugada desta ter\u00e7a-feira (14), pelas oitavas de final dos respectivos torneios. Entre os homens, que buscam um t\u00edtulo in\u00e9dito, o desafio brasileiro ser\u00e1 contra o Jap\u00e3o, a partir das 2h30 (hor\u00e1rio","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/ejornais.com.br\/#website"},"breadcrumb":{"@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/#breadcrumblist"},"author":{"@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author"},"creator":{"@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author"},"datePublished":"2026-07-13T21:33:47-03:00","dateModified":"2026-07-13T21:33:47-03:00"},{"@type":"WebSite","@id":"https:\/\/ejornais.com.br\/#website","url":"https:\/\/ejornais.com.br\/","name":"eJornais","description":"Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/ejornais.com.br\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"eJornais - Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo","og:type":"article","og:title":"Invictas, sele\u00e7\u00f5es do Brasil jogam oitavas do Mundial de v\u00f4lei sentado - eJornais","og:description":"Por MRNews As sele\u00e7\u00f5es masculina e feminina de v\u00f4lei sentado, que disputam o Campeonato Mundial da modalidade em Hanghzou (China), voltam a quadra na madrugada desta ter\u00e7a-feira (14), pelas oitavas de final dos respectivos torneios. Entre os homens, que buscam um t\u00edtulo in\u00e9dito, o desafio brasileiro ser\u00e1 contra o Jap\u00e3o, a partir das 2h30 (hor\u00e1rio","og:url":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/","article:published_time":"2026-07-14T00:33:47+00:00","article:modified_time":"2026-07-14T00:33:47+00:00","twitter:card":"summary_large_image","twitter:title":"Invictas, sele\u00e7\u00f5es do Brasil jogam oitavas do Mundial de v\u00f4lei sentado - eJornais","twitter:description":"Por MRNews As sele\u00e7\u00f5es masculina e feminina de v\u00f4lei sentado, que disputam o Campeonato Mundial da modalidade em Hanghzou (China), voltam a quadra na madrugada desta ter\u00e7a-feira (14), pelas oitavas de final dos respectivos torneios. Entre os homens, que buscam um t\u00edtulo in\u00e9dito, o desafio brasileiro ser\u00e1 contra o Jap\u00e3o, a partir das 2h30 (hor\u00e1rio"},"aioseo_meta_data":[],"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ejornais.com.br\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/\" title=\"Cat\u00e1logo de Jornais\">Cat\u00e1logo de Jornais<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tInvictas, sele\u00e7\u00f5es do Brasil jogam oitavas do Mundial de v\u00f4lei sentado\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/ejornais.com.br"},{"label":"Cat\u00e1logo de Jornais","link":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/"},{"label":"Invictas, sele\u00e7\u00f5es do Brasil jogam oitavas do Mundial de v\u00f4lei sentado","link":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/"}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts\/69058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=69058"}],"version-history":[{"count":0,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts\/69058\/revisions"}],"wp:attachment":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=69058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=69058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=69058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}