{"id":69065,"date":"2026-07-14T01:41:42","date_gmt":"2026-07-14T04:41:42","guid":{"rendered":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/14\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\/"},"modified":"2026-07-14T01:41:42","modified_gmt":"2026-07-14T04:41:42","slug":"homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine","status":"publish","type":"post","link":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/14\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\/","title":{"rendered":"Homem \u00e9 morto durante a\u00e7\u00e3o do servi\u00e7o de imigra\u00e7\u00e3o dos EUA no Maine"},"content":{"rendered":"<p> Por MRNews<br \/>\n<\/p>\n<div>\n<p><strong>Um homem cuja identidade n\u00e3o foi confirmada foi morto a tiros, na manh\u00e3 desta segunda-feira (13), na cidade de Biddeford, no Maine, nos Estados Unidos<\/strong>. Segundo autoridades locais, o homem foi baleado durante uma a\u00e7\u00e3o do Servi\u00e7o de Imigra\u00e7\u00e3o e Alf\u00e2ndega (ICE, do ingl\u00eas).<\/p>\n<p><strong>Em nota, a governadora democrata Janet Mills classificou o epis\u00f3dio como um \u201ctiroteio fatal\u201d<\/strong>. Segundo ela, policiais e representantes de \u00f3rg\u00e3os federais e estaduais se deslocaram imediatamente para o local e est\u00e3o apurando a ocorr\u00eancia.<\/p>\n<p>O presidente da C\u00e2mara dos Representantes do Maine, o tamb\u00e9m democrata Ryan Fecteau, usou as redes sociais para assegurar que o caso abalou toda a comunidade. \u201cEstamos com o cora\u00e7\u00e3o partido por algu\u00e9m ter perdido a vida\u201d, escreveu\u00a0Fecteau, cobrando esclarecimentos das autoridades respons\u00e1veis pela opera\u00e7\u00e3o que culminou com o tiroteio e um \u00f3bito.<\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/07\/13\/congresso-se-aproxima-do-recesso-sem-votar-pec-6x1-e-pl-da-misoginia\/\">Congresso se aproxima do recesso sem votar PEC 6\u00d71 e PL da Misoginia<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/07\/13\/cantor-e-compositor-joao-bosco-completa-80-anos\/\">Cantor e compositor Jo\u00e3o Bosco completa 80 anos<\/a><\/strong><\/p>\n<p>\u201cMerecemos respostas sobre por que a for\u00e7a letal foi usada e por que uma opera\u00e7\u00e3o estava sendo realizada em nossas ruas\u201d, acrescentou Fecteau, destacando que os imigrantes s\u00e3o \u201cparticularmente afetados por essa viol\u00eancia\u201d.<\/p>\n<p><strong>Segundo sites de not\u00edcias locais, o homem morto \u00e9 um colombiano de cerca de 25 anos cujo ve\u00edculo, aparentemente, foi abordado por agentes de imigra\u00e7\u00e3o. <\/strong><\/p>\n<p>O caso ocorre menos de uma semana ap\u00f3s um agente do ICE matar, tamb\u00e9m a tiros, um motorista mexicano identificado como Lorenzo Salgado Araujo, durante uma abordagem, em Houston, no Texas.<\/p>\n<p>A morte da \u00faltima ter\u00e7a-feira (7) j\u00e1 tinha reacendido os protestos e cr\u00edticas ao uso da viol\u00eancia estatal desmedida contra imigrantes. <strong>A desta manh\u00e3 suscitou uma nova onda de protestos que, segundo o site Portland Press Herald, do Maine, vem aumentando\u00a0ao longo das \u00faltimas horas.<\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/07\/13\/tjsp-absolve-empresario-thiago-brennand-de-acusacao-de-estupro\/\">TJSP absolve empres\u00e1rio Thiago Brennand de acusa\u00e7\u00e3o de estupro<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/07\/13\/invictas-selecoes-do-brasil-jogam-oitavas-do-mundial-de-volei-sentado\/\">Invictas, sele\u00e7\u00f5es do Brasil jogam oitavas do Mundial de v\u00f4lei sentado<\/a><\/strong><\/p>\n<p>A senadora republicana Susan Collins usou as\u00a0redes sociais para pedir uma investiga\u00e7\u00e3o imparcial dos fatos. \u201cO tiroteio exige uma investiga\u00e7\u00e3o completa e imparcial do que aconteceu. Pelo que entendo, a pol\u00edcia de Biddeford garantiu a seguran\u00e7a do local e o FBI est\u00e1 investigando\u201d, escreveu\u00a0a senadora.<\/p>\n<p>Eleita por Biddeford, a deputada democrata Chellie Pingree afirmou estar \u201cprofundamente perturbada e indignada\u201d. Depois, em um segundo v\u00eddeo divulgado nas redes sociais, se somou aos que cobram \u201cuma investiga\u00e7\u00e3o completa e independente\u201d.<\/p>\n<p>\u201cAinda h\u00e1 muitas inc\u00f3gnitas, mas deixem-me ser clara: agentes federais de fiscaliza\u00e7\u00e3o de imigra\u00e7\u00e3o n\u00e3o deveriam usar for\u00e7a letal contra ningu\u00e9m em nossas comunidades \u2014 independentemente de seu status migrat\u00f3rio ou das circunst\u00e2ncias que cercam a \u2018atividade de fiscaliza\u00e7\u00e3o direcionada\u2019. Ponto final\u201d, escreveu Chellie.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por MRNews Um homem cuja identidade n\u00e3o foi confirmada foi morto a tiros, na manh\u00e3 desta segunda-feira (13), na cidade<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-69065","post","type-post","status-publish","format-standard","hentry","category-ejornais"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Por MRNews Um homem cuja identidade n\u00e3o foi confirmada foi morto a tiros, na manh\u00e3 desta segunda-feira (13), na cidade de Biddeford, no Maine, nos Estados Unidos. Segundo autoridades locais, o homem foi baleado durante uma a\u00e7\u00e3o do Servi\u00e7o de Imigra\u00e7\u00e3o e Alf\u00e2ndega (ICE, do ingl\u00eas). Em nota, a governadora democrata Janet Mills classificou o\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ejornais.com.br\/index.php\/2026\/07\/14\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"eJornais - Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Homem \u00e9 morto durante a\u00e7\u00e3o do servi\u00e7o de imigra\u00e7\u00e3o dos EUA no Maine - eJornais\" \/>\n\t\t<meta property=\"og:description\" content=\"Por MRNews Um homem cuja identidade n\u00e3o foi confirmada foi morto a tiros, na manh\u00e3 desta segunda-feira (13), na cidade de Biddeford, no Maine, nos Estados Unidos. Segundo autoridades locais, o homem foi baleado durante uma a\u00e7\u00e3o do Servi\u00e7o de Imigra\u00e7\u00e3o e Alf\u00e2ndega (ICE, do ingl\u00eas). Em nota, a governadora democrata Janet Mills classificou o\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ejornais.com.br\/index.php\/2026\/07\/14\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-14T04:41:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-14T04:41:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Homem \u00e9 morto durante a\u00e7\u00e3o do servi\u00e7o de imigra\u00e7\u00e3o dos EUA no Maine - eJornais\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Por MRNews Um homem cuja identidade n\u00e3o foi confirmada foi morto a tiros, na manh\u00e3 desta segunda-feira (13), na cidade de Biddeford, no Maine, nos Estados Unidos. Segundo autoridades locais, o homem foi baleado durante uma a\u00e7\u00e3o do Servi\u00e7o de Imigra\u00e7\u00e3o e Alf\u00e2ndega (ICE, do ingl\u00eas). Em nota, a governadora democrata Janet Mills classificou o\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\\\/#blogposting\",\"name\":\"Homem \\u00e9 morto durante a\\u00e7\\u00e3o do servi\\u00e7o de imigra\\u00e7\\u00e3o dos EUA no Maine - eJornais\",\"headline\":\"Homem \\u00e9 morto durante a\\u00e7\\u00e3o do servi\\u00e7o de imigra\\u00e7\\u00e3o dos EUA no Maine\",\"author\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#organization\"},\"datePublished\":\"2026-07-14T01:41:42-03:00\",\"dateModified\":\"2026-07-14T01:41:42-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\\\/#webpage\"},\"articleSection\":\"Cat\\u00e1logo de Jornais\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/ejornais.com.br\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/#listItem\",\"name\":\"Cat\\u00e1logo de Jornais\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/#listItem\",\"position\":2,\"name\":\"Cat\\u00e1logo de Jornais\",\"item\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\\\/#listItem\",\"name\":\"Homem \\u00e9 morto durante a\\u00e7\\u00e3o do servi\\u00e7o de imigra\\u00e7\\u00e3o dos EUA no Maine\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\\\/#listItem\",\"position\":3,\"name\":\"Homem \\u00e9 morto durante a\\u00e7\\u00e3o do servi\\u00e7o de imigra\\u00e7\\u00e3o dos EUA no Maine\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/#listItem\",\"name\":\"Cat\\u00e1logo de Jornais\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#organization\",\"name\":\"eJornais\",\"description\":\"Cat\\u00e1logo de Jornais no mundo, Not\\u00edcias, Blog e Esportes ao vivo\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/\",\"name\":\"admin1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\\\/#webpage\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\\\/\",\"name\":\"Homem \\u00e9 morto durante a\\u00e7\\u00e3o do servi\\u00e7o de imigra\\u00e7\\u00e3o dos EUA no Maine - eJornais\",\"description\":\"Por MRNews Um homem cuja identidade n\\u00e3o foi confirmada foi morto a tiros, na manh\\u00e3 desta segunda-feira (13), na cidade de Biddeford, no Maine, nos Estados Unidos. Segundo autoridades locais, o homem foi baleado durante uma a\\u00e7\\u00e3o do Servi\\u00e7o de Imigra\\u00e7\\u00e3o e Alf\\u00e2ndega (ICE, do ingl\\u00eas). Em nota, a governadora democrata Janet Mills classificou o\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\"},\"datePublished\":\"2026-07-14T01:41:42-03:00\",\"dateModified\":\"2026-07-14T01:41:42-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#website\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/\",\"name\":\"eJornais\",\"description\":\"Cat\\u00e1logo de Jornais no mundo, Not\\u00edcias, Blog e Esportes ao vivo\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Homem \u00e9 morto durante a\u00e7\u00e3o do servi\u00e7o de imigra\u00e7\u00e3o dos EUA no Maine - eJornais","description":"Por MRNews Um homem cuja identidade n\u00e3o foi confirmada foi morto a tiros, na manh\u00e3 desta segunda-feira (13), na cidade de Biddeford, no Maine, nos Estados Unidos. Segundo autoridades locais, o homem foi baleado durante uma a\u00e7\u00e3o do Servi\u00e7o de Imigra\u00e7\u00e3o e Alf\u00e2ndega (ICE, do ingl\u00eas). Em nota, a governadora democrata Janet Mills classificou o","canonical_url":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/14\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/14\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\/#blogposting","name":"Homem \u00e9 morto durante a\u00e7\u00e3o do servi\u00e7o de imigra\u00e7\u00e3o dos EUA no Maine - eJornais","headline":"Homem \u00e9 morto durante a\u00e7\u00e3o do servi\u00e7o de imigra\u00e7\u00e3o dos EUA no Maine","author":{"@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author"},"publisher":{"@id":"https:\/\/ejornais.com.br\/#organization"},"datePublished":"2026-07-14T01:41:42-03:00","dateModified":"2026-07-14T01:41:42-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/14\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\/#webpage"},"isPartOf":{"@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/14\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\/#webpage"},"articleSection":"Cat\u00e1logo de Jornais"},{"@type":"BreadcrumbList","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/14\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ejornais.com.br#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/ejornais.com.br","nextItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/#listItem","name":"Cat\u00e1logo de Jornais"}},{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/#listItem","position":2,"name":"Cat\u00e1logo de Jornais","item":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/14\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\/#listItem","name":"Homem \u00e9 morto durante a\u00e7\u00e3o do servi\u00e7o de imigra\u00e7\u00e3o dos EUA no Maine"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/14\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\/#listItem","position":3,"name":"Homem \u00e9 morto durante a\u00e7\u00e3o do servi\u00e7o de imigra\u00e7\u00e3o dos EUA no Maine","previousItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/#listItem","name":"Cat\u00e1logo de Jornais"}}]},{"@type":"Organization","@id":"https:\/\/ejornais.com.br\/#organization","name":"eJornais","description":"Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo","url":"https:\/\/ejornais.com.br\/"},{"@type":"Person","@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author","url":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/","name":"admin1","image":{"@type":"ImageObject","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/14\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin1"}},{"@type":"WebPage","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/14\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\/#webpage","url":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/14\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\/","name":"Homem \u00e9 morto durante a\u00e7\u00e3o do servi\u00e7o de imigra\u00e7\u00e3o dos EUA no Maine - eJornais","description":"Por MRNews Um homem cuja identidade n\u00e3o foi confirmada foi morto a tiros, na manh\u00e3 desta segunda-feira (13), na cidade de Biddeford, no Maine, nos Estados Unidos. Segundo autoridades locais, o homem foi baleado durante uma a\u00e7\u00e3o do Servi\u00e7o de Imigra\u00e7\u00e3o e Alf\u00e2ndega (ICE, do ingl\u00eas). Em nota, a governadora democrata Janet Mills classificou o","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/ejornais.com.br\/#website"},"breadcrumb":{"@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/14\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\/#breadcrumblist"},"author":{"@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author"},"creator":{"@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author"},"datePublished":"2026-07-14T01:41:42-03:00","dateModified":"2026-07-14T01:41:42-03:00"},{"@type":"WebSite","@id":"https:\/\/ejornais.com.br\/#website","url":"https:\/\/ejornais.com.br\/","name":"eJornais","description":"Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/ejornais.com.br\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"eJornais - Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo","og:type":"article","og:title":"Homem \u00e9 morto durante a\u00e7\u00e3o do servi\u00e7o de imigra\u00e7\u00e3o dos EUA no Maine - eJornais","og:description":"Por MRNews Um homem cuja identidade n\u00e3o foi confirmada foi morto a tiros, na manh\u00e3 desta segunda-feira (13), na cidade de Biddeford, no Maine, nos Estados Unidos. Segundo autoridades locais, o homem foi baleado durante uma a\u00e7\u00e3o do Servi\u00e7o de Imigra\u00e7\u00e3o e Alf\u00e2ndega (ICE, do ingl\u00eas). Em nota, a governadora democrata Janet Mills classificou o","og:url":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/14\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\/","article:published_time":"2026-07-14T04:41:42+00:00","article:modified_time":"2026-07-14T04:41:42+00:00","twitter:card":"summary_large_image","twitter:title":"Homem \u00e9 morto durante a\u00e7\u00e3o do servi\u00e7o de imigra\u00e7\u00e3o dos EUA no Maine - eJornais","twitter:description":"Por MRNews Um homem cuja identidade n\u00e3o foi confirmada foi morto a tiros, na manh\u00e3 desta segunda-feira (13), na cidade de Biddeford, no Maine, nos Estados Unidos. Segundo autoridades locais, o homem foi baleado durante uma a\u00e7\u00e3o do Servi\u00e7o de Imigra\u00e7\u00e3o e Alf\u00e2ndega (ICE, do ingl\u00eas). Em nota, a governadora democrata Janet Mills classificou o"},"aioseo_meta_data":[],"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ejornais.com.br\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/\" title=\"Cat\u00e1logo de Jornais\">Cat\u00e1logo de Jornais<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHomem \u00e9 morto durante a\u00e7\u00e3o do servi\u00e7o de imigra\u00e7\u00e3o dos EUA no Maine\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/ejornais.com.br"},{"label":"Cat\u00e1logo de Jornais","link":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/"},{"label":"Homem \u00e9 morto durante a\u00e7\u00e3o do servi\u00e7o de imigra\u00e7\u00e3o dos EUA no Maine","link":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/14\/homem-e-morto-durante-acao-do-servico-de-imigracao-dos-eua-no-maine\/"}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts\/69065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=69065"}],"version-history":[{"count":0,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts\/69065\/revisions"}],"wp:attachment":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=69065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=69065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=69065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}