{"id":69113,"date":"2026-07-15T00:42:37","date_gmt":"2026-07-15T03:42:37","guid":{"rendered":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/15\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\/"},"modified":"2026-07-15T00:42:37","modified_gmt":"2026-07-15T03:42:37","slug":"pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha","status":"publish","type":"post","link":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/15\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\/","title":{"rendered":"Pesquisa do Procon-JP encontra diferen\u00e7a de mais de R$ 32 no pre\u00e7o do botij\u00e3o do g\u00e1s de cozinha"},"content":{"rendered":"<p><\/p>\n<div>\n<p>Pesquisa da Secretaria Municipal de Prote\u00e7\u00e3o e Defesa do Consumidor de Jo\u00e3o Pessoa (Procon-JP) para pre\u00e7o do botij\u00e3o de 13 quilos do g\u00e1s de cozinha registrou diferen\u00e7a de R$ 32,01 nos pontos de revenda da Capital, com o produto oscilando entre R$ 92,99 (Posto Via Oeste \u2013 Alto do Mateus) e R$ 125,00 (Almir G\u00e1s \u2013 Mandacaru) para pagamento \u00e0 vista, com varia\u00e7\u00e3o de 34,42% e m\u00e9dia de R$ 115,31.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><\/figure>\n<figure class=\"wp-block-image size-large\"><\/figure>\n<\/figure>\n<p>O levantamento constatou, ainda, que os outros menores pre\u00e7os foram encontrados a R$ 108,00 (Jampa G\u00e1s \u2013 Cristo) e a R$ 110,00 (Alex G\u00e1s e Dep\u00f3sito Novais \u2013 Cruz das Armas, SOS G\u00e1s e Andr\u00e9 G\u00e1s \u2013 Torre, Todo G\u00e1s \u2013 Treze de Maio e Abigail G\u00e1s \u2013 Mandacaru).<\/p>\n<p>Para pagamento no cart\u00e3o, o Procon-JP registra que o pre\u00e7o do produto est\u00e1 sendo praticado entre R$ 97,99 (Posto Via Oeste \u2013 Alto do Mateus) e R$ 130,00 (Almir G\u00e1s \u2013 Mandacaru e Kiko G\u00e1s \u2013 Alto do Mateus). O segundo menor pre\u00e7o est\u00e1 em R$ 110,00 (Jampa G\u00e1s \u2013 Cristo).<\/p>\n<p>A pesquisa foi realizada em 36 estabelecimentos, nesta segunda-feira (13), em 32 bairros da Capital e traz, ainda, pre\u00e7os do vasilhame completo (recipiente e g\u00e1s) de 13 quilos.<\/p>\n<p><strong>G\u00e1s com recipiente <\/strong>\u2013 A pesquisa do Procon-JP d\u00e1 a oportunidade, ainda, do consumidor pessoense adquirir o botij\u00e3o de 13 quilos do g\u00e1s de cozinha junto com o recipiente, cujos pre\u00e7os oscilam entre R$ 250,00 (Neto G\u00e1s \u2013 Jaguaribe) e Posto Via Oeste \u2013 Alto do Mateus) e R$ 340,00 (Banc\u00e1rios G\u00e1s \u2013 Banc\u00e1rios) para pagamento \u00e0 vista.<\/p>\n<p>O segundo menor pre\u00e7o foi encontrado a R$ 260,00 (Rei do G\u00e1s \u2013 Castelo Branco) e o terceiro menor a R$ 270,00 (Alex G\u00e1s \u2013 Cruz das Armas).<\/p>\n<p>Para pagamento no cart\u00e3o, o produto oscila entre R$ 250,00 (Posto Via Oeste \u2013 Alto do Mateus) e R$ 350,00 (Banc\u00e1rios G\u00e1s \u2013 Banc\u00e1rios e Vit\u00f3ria G\u00e1s \u2013 Mandacaru). A diferen\u00e7a est\u00e1 em R$ 110,00. Os outros menores pre\u00e7os est\u00e3o sendo comercializados a R$ 260,00 (Neto G\u00e1s \u2013 Jaguaribe), a 270,00 (Rei do G\u00e1s \u2013 Castelo Branco) e R$ 280 (Alex G\u00e1s \u2013 Cruz das Armas).<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pesquisa da Secretaria Municipal de Prote\u00e7\u00e3o e Defesa do Consumidor de Jo\u00e3o Pessoa (Procon-JP) para pre\u00e7o do botij\u00e3o de 13<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-69113","post","type-post","status-publish","format-standard","hentry","category-ejornais"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Pesquisa da Secretaria Municipal de Prote\u00e7\u00e3o e Defesa do Consumidor de Jo\u00e3o Pessoa (Procon-JP) para pre\u00e7o do botij\u00e3o de 13 quilos do g\u00e1s de cozinha registrou diferen\u00e7a de R$ 32,01 nos pontos de revenda da Capital, com o produto oscilando entre R$ 92,99 (Posto Via Oeste \u2013 Alto do Mateus) e R$ 125,00 (Almir G\u00e1s\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ejornais.com.br\/index.php\/2026\/07\/15\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"eJornais - Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pesquisa do Procon-JP encontra diferen\u00e7a de mais de R$ 32 no pre\u00e7o do botij\u00e3o do g\u00e1s de cozinha - eJornais\" \/>\n\t\t<meta property=\"og:description\" content=\"Pesquisa da Secretaria Municipal de Prote\u00e7\u00e3o e Defesa do Consumidor de Jo\u00e3o Pessoa (Procon-JP) para pre\u00e7o do botij\u00e3o de 13 quilos do g\u00e1s de cozinha registrou diferen\u00e7a de R$ 32,01 nos pontos de revenda da Capital, com o produto oscilando entre R$ 92,99 (Posto Via Oeste \u2013 Alto do Mateus) e R$ 125,00 (Almir G\u00e1s\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ejornais.com.br\/index.php\/2026\/07\/15\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-15T03:42:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-15T03:42:37+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pesquisa do Procon-JP encontra diferen\u00e7a de mais de R$ 32 no pre\u00e7o do botij\u00e3o do g\u00e1s de cozinha - eJornais\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Pesquisa da Secretaria Municipal de Prote\u00e7\u00e3o e Defesa do Consumidor de Jo\u00e3o Pessoa (Procon-JP) para pre\u00e7o do botij\u00e3o de 13 quilos do g\u00e1s de cozinha registrou diferen\u00e7a de R$ 32,01 nos pontos de revenda da Capital, com o produto oscilando entre R$ 92,99 (Posto Via Oeste \u2013 Alto do Mateus) e R$ 125,00 (Almir G\u00e1s\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/15\\\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\\\/#blogposting\",\"name\":\"Pesquisa do Procon-JP encontra diferen\\u00e7a de mais de R$ 32 no pre\\u00e7o do botij\\u00e3o do g\\u00e1s de cozinha - eJornais\",\"headline\":\"Pesquisa do Procon-JP encontra diferen\\u00e7a de mais de R$ 32 no pre\\u00e7o do botij\\u00e3o do g\\u00e1s de cozinha\",\"author\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#organization\"},\"datePublished\":\"2026-07-15T00:42:37-03:00\",\"dateModified\":\"2026-07-15T00:42:37-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/15\\\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/15\\\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\\\/#webpage\"},\"articleSection\":\"Cat\\u00e1logo de Jornais\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/15\\\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/ejornais.com.br\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/#listItem\",\"name\":\"Cat\\u00e1logo de Jornais\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/#listItem\",\"position\":2,\"name\":\"Cat\\u00e1logo de Jornais\",\"item\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/15\\\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\\\/#listItem\",\"name\":\"Pesquisa do Procon-JP encontra diferen\\u00e7a de mais de R$ 32 no pre\\u00e7o do botij\\u00e3o do g\\u00e1s de cozinha\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/15\\\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\\\/#listItem\",\"position\":3,\"name\":\"Pesquisa do Procon-JP encontra diferen\\u00e7a de mais de R$ 32 no pre\\u00e7o do botij\\u00e3o do g\\u00e1s de cozinha\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/category\\\/ejornais\\\/#listItem\",\"name\":\"Cat\\u00e1logo de Jornais\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#organization\",\"name\":\"eJornais\",\"description\":\"Cat\\u00e1logo de Jornais no mundo, Not\\u00edcias, Blog e Esportes ao vivo\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/\",\"name\":\"admin1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/15\\\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/15\\\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\\\/#webpage\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/15\\\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\\\/\",\"name\":\"Pesquisa do Procon-JP encontra diferen\\u00e7a de mais de R$ 32 no pre\\u00e7o do botij\\u00e3o do g\\u00e1s de cozinha - eJornais\",\"description\":\"Pesquisa da Secretaria Municipal de Prote\\u00e7\\u00e3o e Defesa do Consumidor de Jo\\u00e3o Pessoa (Procon-JP) para pre\\u00e7o do botij\\u00e3o de 13 quilos do g\\u00e1s de cozinha registrou diferen\\u00e7a de R$ 32,01 nos pontos de revenda da Capital, com o produto oscilando entre R$ 92,99 (Posto Via Oeste \\u2013 Alto do Mateus) e R$ 125,00 (Almir G\\u00e1s\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/2026\\\/07\\\/15\\\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/index.php\\\/author\\\/admin1\\\/#author\"},\"datePublished\":\"2026-07-15T00:42:37-03:00\",\"dateModified\":\"2026-07-15T00:42:37-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#website\",\"url\":\"https:\\\/\\\/ejornais.com.br\\\/\",\"name\":\"eJornais\",\"description\":\"Cat\\u00e1logo de Jornais no mundo, Not\\u00edcias, Blog e Esportes ao vivo\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/ejornais.com.br\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Pesquisa do Procon-JP encontra diferen\u00e7a de mais de R$ 32 no pre\u00e7o do botij\u00e3o do g\u00e1s de cozinha - eJornais","description":"Pesquisa da Secretaria Municipal de Prote\u00e7\u00e3o e Defesa do Consumidor de Jo\u00e3o Pessoa (Procon-JP) para pre\u00e7o do botij\u00e3o de 13 quilos do g\u00e1s de cozinha registrou diferen\u00e7a de R$ 32,01 nos pontos de revenda da Capital, com o produto oscilando entre R$ 92,99 (Posto Via Oeste \u2013 Alto do Mateus) e R$ 125,00 (Almir G\u00e1s","canonical_url":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/15\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/15\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\/#blogposting","name":"Pesquisa do Procon-JP encontra diferen\u00e7a de mais de R$ 32 no pre\u00e7o do botij\u00e3o do g\u00e1s de cozinha - eJornais","headline":"Pesquisa do Procon-JP encontra diferen\u00e7a de mais de R$ 32 no pre\u00e7o do botij\u00e3o do g\u00e1s de cozinha","author":{"@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author"},"publisher":{"@id":"https:\/\/ejornais.com.br\/#organization"},"datePublished":"2026-07-15T00:42:37-03:00","dateModified":"2026-07-15T00:42:37-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/15\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\/#webpage"},"isPartOf":{"@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/15\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\/#webpage"},"articleSection":"Cat\u00e1logo de Jornais"},{"@type":"BreadcrumbList","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/15\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ejornais.com.br#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/ejornais.com.br","nextItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/#listItem","name":"Cat\u00e1logo de Jornais"}},{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/#listItem","position":2,"name":"Cat\u00e1logo de Jornais","item":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/15\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\/#listItem","name":"Pesquisa do Procon-JP encontra diferen\u00e7a de mais de R$ 32 no pre\u00e7o do botij\u00e3o do g\u00e1s de cozinha"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/15\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\/#listItem","position":3,"name":"Pesquisa do Procon-JP encontra diferen\u00e7a de mais de R$ 32 no pre\u00e7o do botij\u00e3o do g\u00e1s de cozinha","previousItem":{"@type":"ListItem","@id":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/#listItem","name":"Cat\u00e1logo de Jornais"}}]},{"@type":"Organization","@id":"https:\/\/ejornais.com.br\/#organization","name":"eJornais","description":"Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo","url":"https:\/\/ejornais.com.br\/"},{"@type":"Person","@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author","url":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/","name":"admin1","image":{"@type":"ImageObject","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/15\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin1"}},{"@type":"WebPage","@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/15\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\/#webpage","url":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/15\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\/","name":"Pesquisa do Procon-JP encontra diferen\u00e7a de mais de R$ 32 no pre\u00e7o do botij\u00e3o do g\u00e1s de cozinha - eJornais","description":"Pesquisa da Secretaria Municipal de Prote\u00e7\u00e3o e Defesa do Consumidor de Jo\u00e3o Pessoa (Procon-JP) para pre\u00e7o do botij\u00e3o de 13 quilos do g\u00e1s de cozinha registrou diferen\u00e7a de R$ 32,01 nos pontos de revenda da Capital, com o produto oscilando entre R$ 92,99 (Posto Via Oeste \u2013 Alto do Mateus) e R$ 125,00 (Almir G\u00e1s","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/ejornais.com.br\/#website"},"breadcrumb":{"@id":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/15\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\/#breadcrumblist"},"author":{"@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author"},"creator":{"@id":"https:\/\/ejornais.com.br\/index.php\/author\/admin1\/#author"},"datePublished":"2026-07-15T00:42:37-03:00","dateModified":"2026-07-15T00:42:37-03:00"},{"@type":"WebSite","@id":"https:\/\/ejornais.com.br\/#website","url":"https:\/\/ejornais.com.br\/","name":"eJornais","description":"Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/ejornais.com.br\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"eJornais - Cat\u00e1logo de Jornais no mundo, Not\u00edcias, Blog e Esportes ao vivo","og:type":"article","og:title":"Pesquisa do Procon-JP encontra diferen\u00e7a de mais de R$ 32 no pre\u00e7o do botij\u00e3o do g\u00e1s de cozinha - eJornais","og:description":"Pesquisa da Secretaria Municipal de Prote\u00e7\u00e3o e Defesa do Consumidor de Jo\u00e3o Pessoa (Procon-JP) para pre\u00e7o do botij\u00e3o de 13 quilos do g\u00e1s de cozinha registrou diferen\u00e7a de R$ 32,01 nos pontos de revenda da Capital, com o produto oscilando entre R$ 92,99 (Posto Via Oeste \u2013 Alto do Mateus) e R$ 125,00 (Almir G\u00e1s","og:url":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/15\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\/","article:published_time":"2026-07-15T03:42:37+00:00","article:modified_time":"2026-07-15T03:42:37+00:00","twitter:card":"summary_large_image","twitter:title":"Pesquisa do Procon-JP encontra diferen\u00e7a de mais de R$ 32 no pre\u00e7o do botij\u00e3o do g\u00e1s de cozinha - eJornais","twitter:description":"Pesquisa da Secretaria Municipal de Prote\u00e7\u00e3o e Defesa do Consumidor de Jo\u00e3o Pessoa (Procon-JP) para pre\u00e7o do botij\u00e3o de 13 quilos do g\u00e1s de cozinha registrou diferen\u00e7a de R$ 32,01 nos pontos de revenda da Capital, com o produto oscilando entre R$ 92,99 (Posto Via Oeste \u2013 Alto do Mateus) e R$ 125,00 (Almir G\u00e1s"},"aioseo_meta_data":[],"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ejornais.com.br\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/\" title=\"Cat\u00e1logo de Jornais\">Cat\u00e1logo de Jornais<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPesquisa do Procon-JP encontra diferen\u00e7a de mais de R$ 32 no pre\u00e7o do botij\u00e3o do g\u00e1s de cozinha\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/ejornais.com.br"},{"label":"Cat\u00e1logo de Jornais","link":"https:\/\/ejornais.com.br\/index.php\/category\/ejornais\/"},{"label":"Pesquisa do Procon-JP encontra diferen\u00e7a de mais de R$ 32 no pre\u00e7o do botij\u00e3o do g\u00e1s de cozinha","link":"https:\/\/ejornais.com.br\/index.php\/2026\/07\/15\/pesquisa-do-procon-jp-encontra-diferenca-de-mais-de-r-32-no-preco-do-botijao-do-gas-de-cozinha\/"}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts\/69113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=69113"}],"version-history":[{"count":0,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/posts\/69113\/revisions"}],"wp:attachment":[{"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=69113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=69113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ejornais.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=69113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}